{"id":2881,"date":"2021-04-13T20:14:26","date_gmt":"2021-04-13T20:14:26","guid":{"rendered":"https:\/\/doratalomran.iq\/%d8%a7%d9%84%d8%a8%d9%84%d8%a7%d8%b7\/"},"modified":"2022-08-25T09:08:24","modified_gmt":"2022-08-25T09:08:24","slug":"%d8%a7%d9%84%d8%a8%d9%84%d8%a7%d8%b7","status":"publish","type":"page","link":"https:\/\/doratalomran.iq\/ar\/%d8%a7%d9%84%d8%a8%d9%84%d8%a7%d8%b7\/","title":{"rendered":"\u0627\u0644\u0628\u0644\u0627\u0637"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_height=\u201dyes\u201d equal_height=\u201dyes\u201d content_placement=\u201dmiddle\u201d css=\u201d.vc_custom_1661418423047{padding-right: 25px !important;padding-left: 25px !important;}\u201d][vc_column width=\u201d1\/2\u2033][vc_column_text]<\/p>\n<h3 style=\"text-align: right;\"><span style=\"color: #d0af84;\">\u062c\u0647\u0632 \u062c\u062f\u0631\u0627\u0646\u0643 \u0648\u0623\u0631\u0636\u064a\u0627\u062a\u0643 \u0628\u0623\u0641\u0636\u0644 \u0645\u0627 \u064a\u0643\u0648\u0646.<\/span><\/h3>\n<p style=\"text-align: right;\">\u0645\u0627 \u064a\u0645\u064a\u0632 \u0627\u0644\u0628\u0644\u0627\u0637 \u0639\u0646 \u063a\u064a\u0631\u0647 \u0645\u0646 \u0645\u0648\u0627\u062f \u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0647\u0648 \u062a\u0639\u062f\u062f \u0627\u0633\u062a\u062e\u062f\u0627\u0645\u0627\u062a\u0647 \u2013 \u062a\u0632\u064a\u064a\u0646 \u062c\u062f\u0631\u0627\u0646 \u0627\u0644\u0645\u0637\u0628\u062e \u0648\u0623\u0631\u0636\u064a\u0627\u062a \u0627\u0644\u062d\u0645\u0627\u0645 \u0641\u064a \u0627\u0644\u0645\u0646\u0632\u0644 \u0648\u0625\u0636\u0627\u0641\u0629 \u0637\u0627\u0628\u0639\u064b\u0627 \u0645\u0645\u064a\u0632\u064b\u0627 \u0625\u0644\u0649 \u0623\u0631\u0636\u064a\u0627\u062a \u0627\u0644\u0645\u0645\u0631\u0627\u062a \u0648\u062c\u062f\u0631\u0627\u0646 \u063a\u0631\u0641\u0629 \u0627\u0644\u0645\u0639\u064a\u0634\u0629.<\/p>\n<p style=\"text-align: right;\">\u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u062a\u0639\u062f\u062f \u0627\u0633\u062a\u062e\u062f\u0627\u0645\u0627\u062a\u0647\u060c \u064a\u062a\u0645\u064a\u0632 \u0627\u0644\u0628\u0644\u0627\u0637 \u0628\u0645\u062c\u0645\u0648\u0639\u0629 \u0643\u0628\u064a\u0631\u0629 \u0645\u0646 \u0627\u0644\u0641\u0648\u0627\u0626\u062f \u0627\u0644\u0639\u0645\u0644\u064a\u0629 \u0623\u064a\u0636\u064b\u0627 \u2013 \u0645\u0645\u0627 \u064a\u062c\u0639\u0644\u0647\u0627 \u0627\u0644\u062d\u0644 \u0627\u0644\u0645\u062b\u0627\u0644\u064a \u0644\u0644\u0623\u0633\u0631 \u0627\u0644\u062d\u062f\u064a\u062b\u0629 \u0643\u0645\u0642\u0627\u0648\u0645\u0629 \u0627\u0644\u0625\u0647\u062a\u0631\u0627\u0621 \u0648\u0627\u0644\u0645\u0627\u0621 \u0648\u0627\u0644\u0628\u0642\u0639\u060c \u0633\u0647\u0648\u0644\u0629 \u0627\u0644\u062a\u0646\u0638\u064a\u0641. \u0632\u064a\u064a\u0646 \u0645\u0646\u0632\u0644\u0643 \u0648\u062a\u0645\u062a\u0639 \u0628\u062c\u0645\u0627\u0644\u064a\u0627\u062a \u0623\u0646\u064a\u0642\u0629 \u062a\u062f\u0648\u0645 \u0644\u0633\u0646\u0648\u0627\u062a \u0637\u0648\u064a\u0644\u0629 \u0648\u062a\u062a\u0637\u0644\u0628 \u0627\u0644\u062d\u062f \u0627\u0644\u0623\u062f\u0646\u0649 \u0645\u0646 \u0627\u0644\u062c\u0647\u062f \u0645\u0646 \u062d\u064a\u062b \u0627\u0644\u0635\u064a\u0627\u0646\u0629 \u0639\u0644\u0649 \u0627\u0644\u0645\u062f\u0649 \u0627\u0644\u0637\u0648\u064a\u0644.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=\u201d1\/2\u2033][vc_single_image image=\u201d2892\u2033 img_size=\u201dfull\u201d css_animation=\u201dappear\u201d][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=\u201d50px\u201d][vc_separator color=\u201dcustom\u201d accent_color=\u201d#1f3854\u2033][vc_empty_space height=\u201d50px\u201d][\/vc_column][\/vc_row][vc_row equal_height=\u201dyes\u201d content_placement=\u201dmiddle\u201d css=\u201d.vc_custom_1661418430110{padding-right: 25px !important;padding-left: 25px !important;}\u201d][vc_column css_animation=\u201dleft-to-right\u201d width=\u201d1\/3\u2033 css=\u201d.vc_custom_1617549158448{background-color: #1f3854 !important;}\u201d]<div class=\"ba-partner effect-1 \">\n\t\t\t\t<div class=\"list-item\"><div class=\"partner-item\">\n\t\t\t\t\t\t\t<a  target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"334\" src=\"https:\/\/doratalomran.iq\/wp-content\/uploads\/2021\/04\/alomran-logo-porcelanosa-white.png\" class=\"attachment-small size-small\" alt=\"\" srcset=\"https:\/\/doratalomran.iq\/wp-content\/uploads\/2021\/04\/alomran-logo-porcelanosa-white.png 500w, https:\/\/doratalomran.iq\/wp-content\/uploads\/2021\/04\/alomran-logo-porcelanosa-white-300x200.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a>\n\t\t\t\t\t\t<\/div><\/div>\n\t\t\t<\/div>[\/vc_column][vc_column css_animation=\u201dleft-to-right\u201d width=\u201d1\/3\u2033][vc_single_image image=\u201d3721\u2033 img_size=\u201dfull\u201d css_animation=\u201dappear\u201d][\/vc_column][vc_column css_animation=\u201dright-to-left\u201d width=\u201d1\/3\u2033][vc_custom_heading text=\u201d\u0628\u0648\u0631\u0633\u064a\u0644\u0627\u0646\u0648\u0633\u0627\u201d font_container=\u201dtag:h3|font_size:30|text_align:right\u201d use_theme_fonts=\u201dyes\u201d css_animation=\u201dleft-to-right\u201d][vc_column_text]<span style=\"color: #d0af84;\">\u0645\u0631\u062c\u0639\u064b\u0627 \u0631\u0626\u064a\u0633\u064a\u064b\u0627 \u0641\u064a \u0643\u0644 \u0645\u0646 \u0627\u0644\u0633\u0648\u0642 \u0627\u0644\u0625\u0633\u0628\u0627\u0646\u064a\u0629 \u0648\u0627\u0644\u062f\u0648\u0644\u064a\u0629.<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u201d.vc_custom_1661418436182{padding-right: 25px !important;padding-left: 25px !important;}\u201d][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: right;\">\u062a\u0645 \u0628\u0646\u0627\u0621 \u0645\u0643\u0627\u0646\u0629 \u0627\u0644\u0634\u0631\u0643\u0629 \u0639\u0644\u0649 \u0642\u064a\u0645 \u0645\u062b\u0644 \u0627\u0644\u0627\u0628\u062a\u0643\u0627\u0631 \u0648\u0627\u0644\u062c\u0648\u062f\u0629 \u0648\u0644\u0643\u0646 \u0639\u0644\u0649 \u0648\u062c\u0647 \u0627\u0644\u062e\u0635\u0648\u0635 \u0627\u0644\u062b\u0642\u0629 \u0627\u0644\u062a\u064a \u0648\u0636\u0639\u062a \u0641\u064a \u0645\u0648\u0627\u0631\u062f\u0647\u0627 \u0627\u0644\u0628\u0634\u0631\u064a\u0629 \u0627\u0644\u062c\u0628\u0627\u0631\u0629 \u0627\u0644\u0645\u0624\u0644\u0641\u0629 \u0645\u0646 \u0645\u0627 \u064a\u0642\u0627\u0631\u0628 \u0627\u06445000 \u0645\u0648\u0638\u0641 \u0645\u0646 \u0627\u0644\u0645\u0647\u0646\u064a\u064a\u0646.<\/p>\n<p style=\"text-align: right;\">\u0644\u0639\u0628 \u062a\u0646\u0648\u064a\u0639 \u0627\u0644\u0625\u0646\u062a\u0627\u062c \u062f\u0648\u0631\u064b\u0627 \u0631\u0626\u064a\u0633\u064a\u064b\u0627 \u0641\u064a \u0646\u0645\u0648 \u0627\u0644\u0645\u062c\u0645\u0648\u0639\u0629 \u0627\u0644\u062a\u064a \u0628\u062f\u0623\u062a \u0641\u064a \u062a\u0635\u0646\u064a\u0639 \u0645\u0646\u062a\u062c \u0648\u0627\u062d\u062f \u0648\u0647\u0648 \u0628\u0644\u0627\u0637 \u0627\u0644\u0633\u064a\u0631\u0627\u0645\u064a\u0643. \u0623\u0645\u0627 \u0627\u0644\u064a\u0648\u0645 \u0641\u062a\u0642\u062f\u0645 \u0634\u0631\u0643\u0627\u062a \u0627\u0644\u0645\u062c\u0645\u0648\u0639\u0629 \u0627\u0644\u062b\u0645\u0627\u0646\u064a\u0629 \u0645\u062c\u0645\u0648\u0639\u0629 \u0648\u0627\u0633\u0639\u0629 \u0645\u0646 \u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u062a\u0631\u0627\u0648\u062d \u0645\u0646 \u0645\u0639\u062f\u0627\u062a \u0627\u0644\u0645\u0637\u0627\u0628\u062e \u0648\u0627\u0644\u062d\u0645\u0627\u0645\u0627\u062a \u0625\u0644\u0649 \u0627\u0644\u0645\u0648\u0627\u062f \u0639\u0627\u0644\u064a\u0629 \u0627\u0644\u062a\u0642\u0646\u064a\u0629 \u0648\u062d\u0644\u0648\u0644 \u0627\u0644\u0628\u0646\u0627\u0621 \u062d\u062f\u064a\u062b\u0629 \u0644\u0644\u0647\u0646\u062f\u0633\u0629 \u0627\u0644\u0645\u0639\u0645\u0627\u0631\u064a\u0629 \u0627\u0644\u0645\u0639\u0627\u0635\u0631\u0629.<\/p>\n<p>[\/vc_column_text][vc_empty_space][vc_btn title=\u201d\u062a\u062d\u0645\u064a\u0644 \u0627\u0644\u0645\u0644\u0641\u201d i_icon_fontawesome=\u201dfas fa-angle-left\u201d css_animation=\u201dflipInY\u201d add_icon=\u201dtrue\u201d link=\u201durl:%2Fwp-content%2Fuploads%2F2022%2F01%2FPOCELANOSA.pdf|target:_blank\u201d][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=\u201d50px\u201d][vc_separator color=\u201dcustom\u201d accent_color=\u201d#1f3854\u2033][vc_empty_space height=\u201d50px\u201d][\/vc_column][\/vc_row][vc_row equal_height=\u201dyes\u201d content_placement=\u201dmiddle\u201d css=\u201d.vc_custom_1661418449239{padding-right: 25px !important;padding-left: 25px !important;}\u201d][vc_column css_animation=\u201dleft-to-right\u201d width=\u201d1\/3\u2033 css=\u201d.vc_custom_1617549158448{background-color: #1f3854 !important;}\u201d]<div class=\"ba-partner effect-1 \">\n\t\t\t\t<div class=\"list-item\"><div class=\"partner-item\">\n\t\t\t\t\t\t\t<a  target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"334\" src=\"https:\/\/doratalomran.iq\/wp-content\/uploads\/2021\/04\/alomran-logo-florim-white.png\" class=\"attachment-small size-small\" alt=\"\" srcset=\"https:\/\/doratalomran.iq\/wp-content\/uploads\/2021\/04\/alomran-logo-florim-white.png 500w, https:\/\/doratalomran.iq\/wp-content\/uploads\/2021\/04\/alomran-logo-florim-white-300x200.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a>\n\t\t\t\t\t\t<\/div><\/div>\n\t\t\t<\/div>[\/vc_column][vc_column css_animation=\u201dleft-to-right\u201d width=\u201d1\/3\u2033][vc_single_image image=\u201d3711\u2033 img_size=\u201dfull\u201d css_animation=\u201dappear\u201d][\/vc_column][vc_column css_animation=\u201dright-to-left\u201d width=\u201d1\/3\u2033][vc_custom_heading text=\u201d\u0641\u0644\u0648\u0631\u064a\u0645\u201d font_container=\u201dtag:h3|font_size:30|text_align:right\u201d use_theme_fonts=\u201dyes\u201d css_animation=\u201dleft-to-right\u201d][vc_column_text]<\/p>\n<p style=\"text-align: right;\"><span style=\"color: #d0af84;\">\u0641\u064a \u0639\u0627\u0645 1962 \u0648\u0644\u062f\u062a \u0641\u0644\u0648\u0631 \u063a\u0631\u064a\u0633 \u0639\u0646\u062f\u0645\u0627 \u0639\u0631\u0651\u0641 \u0627\u0644\u0633\u064a\u062f \u062c\u064a\u0648\u0641\u0627\u0646\u064a \u0644\u0648\u062a\u0634\u064a\u0633\u064a \u0625\u064a\u0637\u0627\u0644\u064a\u0627 \u0639\u0644\u0649 \u0635\u0646\u0627\u0639\u0629 \u0627\u0644\u0643\u0644\u0646\u0643\u0631 \u0645\u0646 \u0642\u0644\u0628 \u0627\u0644\u0645\u0646\u0637\u0642\u0629 \u0627\u0644\u0635\u0646\u0627\u0639\u064a\u0629 \u0633\u0627\u0633\u0648\u0644\u0648. <\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u201d.vc_custom_1661418457006{padding-right: 25px !important;padding-left: 25px !important;}\u201d][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: right;\">\u0641\u0644\u0648\u0631 \u062c\u0631\u064a\u0633 \u0647\u064a \u0627\u0644\u0634\u0631\u0643\u0629 \u0627\u0644\u0625\u064a\u0637\u0627\u0644\u064a\u0629 \u0627\u0644\u0623\u0648\u0644\u0649 \u0627\u0644\u062a\u064a \u062a\u0646\u062a\u062c \u0627\u0644\u0628\u0644\u0627\u0637 \u0627\u0644\u0637\u064a\u0646\u064a \u0627\u0644\u0623\u0628\u064a\u0636 \u0627\u0644\u0645\u062d\u0631\u0648\u0642. \u0641\u064a \u0639\u0627\u0645 1981 \u0643\u0627\u0646\u062a \u0627\u0644\u0634\u0631\u0643\u0629 \u0645\u0646 \u0623\u0648\u0627\u0626\u0644 \u0627\u0644\u0634\u0631\u0643\u0627\u062a \u0641\u064a \u0627\u0644\u0639\u0627\u0644\u0645 \u0644\u062a\u0635\u0646\u064a\u0639 \u0627\u0644\u062e\u0632\u0641 \u0627\u0644\u062d\u062c\u0631\u064a.<\/p>\n<p style=\"text-align: right;\">\u0641\u064a \u0639\u0627\u0645 1992 \u0627\u0646\u062f\u0645\u062c\u062a \u0641\u0644\u0648\u0631 \u062c\u0631\u064a\u0633 \u0645\u0639 \u0643\u0631\u064a\u0645 \u0644\u062a\u0644\u062f \u0641\u0644\u0648\u0631\u064a\u0645. \u0628\u0639\u062f \u0630\u0644\u0643 \u060c \u0634\u0647\u062f \u0647\u0630\u0627 \u0627\u0644\u0623\u062e\u064a\u0631 \u062a\u0648\u0633\u0639\u0627\u064b \u0648\u062a\u0637\u0648\u0631\u0627\u064b \u0645\u0644\u062d\u0648\u0638\u064a\u0646 \u0628\u062f\u0623 \u0628\u0627\u0644\u0627\u0633\u062a\u062d\u0648\u0627\u0630 \u0639\u0644\u0649 \u0633\u064a\u0631\u0627\u0645\u064a\u0643 \u0631\u064a\u0643\u0633 \u0627\u0644\u0641\u0646\u064a \u0641\u064a \u0639\u0627\u0645 1994 \u060c \u0648\u0625\u0646\u0634\u0627\u0621 \u0642\u0633\u0645 \u0625\u062f\u0627\u0631\u0629 \u0627\u0644\u0645\u0634\u0627\u0631\u064a\u0639 \u0641\u064a \u0639\u0627\u0645 1995 \u060c \u0627\u0644\u0645\u0639\u0631\u0648\u0641 \u0627\u0644\u0622\u0646 \u0628\u0627\u0633\u0645 \u062d\u0644\u0648\u0644 \u0641\u0644\u0648\u0631\u064a\u0645 \u060c \u0648\u0625\u0646\u0634\u0627\u0621 \u0641\u0644\u0648\u0631\u064a\u0648\u0645 \u0623\u0645\u0631\u064a\u0643\u0627 \u0641\u064a \u0639\u0627\u0645 2000 \u0644\u062a\u0635\u0628\u062d \u0644\u0627\u0639\u0628\u064b\u0627 \u0631\u0626\u064a\u0633\u064a\u064b\u0627 \u0641\u064a \u0627\u0644\u0633\u0648\u0642 \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u064a\u0629\u060c \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0627\u0633\u062a\u062d\u0648\u0627\u0630 \u0639\u0644\u0649 \u0634\u0631\u0643\u0629 \u0643\u0627\u0633\u0627 \u062f\u0648\u0644\u062a\u0634\u064a \u0643\u0627\u0633\u0627 \u0641\u064a \u0639\u0627\u0645 2000.<\/p>\n<p style=\"text-align: right;\">\u0644\u0627 \u062a\u0632\u0627\u0644 \u0641\u0644\u0648\u0631\u064a\u0645 \u062a\u062a\u0648\u0633\u0639\u060c \u0645\u0639 \u0627\u0641\u062a\u062a\u0627\u062d \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0635\u0627\u0644\u0627\u062a \u0627\u0644\u0639\u0631\u0636 \u0641\u064a \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0645\u062f\u0646 \u0645\u062b\u0644 \u0645\u064a\u0644\u0627\u0646 \u0648\u0646\u064a\u0648\u064a\u0648\u0631\u0643 \u0648\u0633\u0646\u063a\u0627\u0641\u0648\u0631\u0629 \u060c \u0648\u0645\u0624\u062e\u0631\u0627\u064b \u0641\u064a \u0644\u0646\u062f\u0646 \u0648\u0641\u0631\u0627\u0646\u0643\u0641\u0648\u0631\u062a.<br \/>\nFlorim<\/p>\n<p>[\/vc_column_text][vc_empty_space][vc_btn title=\u201d\u062a\u062d\u0645\u064a\u0644 \u0627\u0644\u0645\u0644\u0641\u201d i_icon_fontawesome=\u201dfas fa-angle-left\u201d css_animation=\u201dflipInY\u201d add_icon=\u201dtrue\u201d link=\u201durl:%2Fwp-content%2Fuploads%2F2022%2F01%2FFLORIM.pdf|target:_blank\u201d][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=\u201d50px\u201d][vc_separator color=\u201dcustom\u201d accent_color=\u201d#1f3854\u2033][vc_empty_space height=\u201d50px\u201d][\/vc_column][\/vc_row][vc_row equal_height=\u201dyes\u201d content_placement=\u201dmiddle\u201d css=\u201d.vc_custom_1661418469078{padding-right: 25px !important;padding-left: 25px !important;}\u201d][vc_column css_animation=\u201dleft-to-right\u201d width=\u201d1\/3\u2033 css=\u201d.vc_custom_1617549158448{background-color: #1f3854 !important;}\u201d]<div class=\"ba-partner effect-1 \">\n\t\t\t\t<div class=\"list-item\"><div class=\"partner-item\">\n\t\t\t\t\t\t\t<a  target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"334\" src=\"https:\/\/doratalomran.iq\/wp-content\/uploads\/2021\/04\/alomran-logo-tau-white.png\" class=\"attachment-small size-small\" alt=\"\" srcset=\"https:\/\/doratalomran.iq\/wp-content\/uploads\/2021\/04\/alomran-logo-tau-white.png 500w, https:\/\/doratalomran.iq\/wp-content\/uploads\/2021\/04\/alomran-logo-tau-white-300x200.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a>\n\t\t\t\t\t\t<\/div><\/div>\n\t\t\t<\/div>[\/vc_column][vc_column css_animation=\u201dleft-to-right\u201d width=\u201d1\/3\u2033][vc_single_image image=\u201d3729\u2033 img_size=\u201dfull\u201d css_animation=\u201dappear\u201d][\/vc_column][vc_column css_animation=\u201dright-to-left\u201d width=\u201d1\/3\u2033][vc_custom_heading text=\u201d\u062a\u0627\u0648 \u0633\u064a\u0631\u0627\u0645\u064a\u0643\u0627\u201d font_container=\u201dtag:h3|font_size:30|text_align:right\u201d use_theme_fonts=\u201dyes\u201d css_animation=\u201dleft-to-right\u201d][vc_column_text]<\/p>\n<p style=\"text-align: right;\"><span style=\"color: #d0af84;\">\u062a\u0639\u0632\u0632 \u062a\u0627\u0648 \u0633\u064a\u0631\u0627\u0645\u064a\u0643\u0627 \u0645\u0643\u0627\u0646\u062a\u0647\u0627 \u0643\u0645\u0639\u064a\u0627\u0631 \u0639\u0627\u0644\u0645\u064a \u0641\u064a \u0642\u0637\u0627\u0639 \u0627\u0644\u0633\u064a\u0631\u0627\u0645\u064a\u0643. <\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u201d.vc_custom_1661418475382{padding-right: 25px !important;padding-left: 25px !important;}\u201d][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: right;\">\u0627\u0644\u062c\u0648\u062f\u0629 \u0627\u0644\u0641\u0646\u064a\u0629 \u0648\u0627\u0644\u062c\u0645\u0627\u0644\u064a\u0629\u060c \u0627\u0644\u0625\u0628\u062a\u0643\u0627\u0631 \u0648\u0627\u0644\u062a\u0637\u0648\u064a\u0631 \u0627\u0644\u0645\u0633\u062a\u0645\u0631\u060c \u0627\u0644\u0625\u0644\u062a\u0632\u0627\u0645 \u0627\u0644\u063a\u064a\u0631 \u0642\u0627\u0628\u0644 \u0644\u0644\u062a\u063a\u064a\u0631 \u062a\u062c\u0627\u0647 \u0627\u0644\u0645\u062c\u062a\u0645\u0639 \u0648\u0627\u0644\u0628\u064a\u0626\u0629\u061b \u062c\u0645\u064a\u0639 \u0647\u0630\u0647 \u0627\u0644\u0635\u0641\u0627\u062a \u062a\u062d\u0642\u0642\u062a \u0628\u0641\u0636\u0644 \u062c\u0647\u0648\u062f \u0648\u0625\u0628\u062f\u0627\u0639 \u0648\u062a\u0641\u0627\u0646\u064a \u0641\u0631\u064a\u0642 \u0644\u0627 \u064a\u0642\u062f\u0631 \u0628\u062b\u0645\u0646.<\/p>\n<p>\u0628\u0639\u062f \u062e\u0628\u0631\u0629 \u0646\u0635\u0641 \u0642\u0631\u0646 \u062a\u062a\u062c\u0647 \u062a\u0627\u0648 \u0627\u0644\u0622\u0646 \u0646\u062d\u0648 \u062a\u062d\u062f\u064a\u0627\u062a \u062c\u062f\u064a\u062f\u0629 \u0628\u0639\u0642\u0644\u064a\u0629 \u0646\u0627\u0636\u062c\u0629 \u0648\u0628\u062f\u0631\u0627\u064a\u0629 \u0645\u0643\u062a\u0633\u0628\u0629 \u0639\u0628\u0631 \u062a\u0627\u0631\u064a\u062e\u0647\u0627\u060c \u0648\u0627\u0644\u0623\u0647\u0645 \u0645\u0646 \u0630\u0644\u0643 \u0628\u062d\u0645\u0627\u0633 \u0648\u0634\u063a\u0641 \u0645\u062a\u062c\u062f\u062f.<\/p>\n<p>[\/vc_column_text][vc_empty_space][vc_btn title=\u201d\u062a\u062d\u0645\u064a\u0644 \u0627\u0644\u0645\u0644\u0641\u201d i_icon_fontawesome=\u201dfas fa-angle-left\u201d css_animation=\u201dflipInY\u201d add_icon=\u201dtrue\u201d link=\u201durl:%2Fwp-content%2Fuploads%2F2022%2F01%2FTAU.pdf|target:_blank\u201d][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=\u201d50px\u201d][vc_separator color=\u201dcustom\u201d accent_color=\u201d#1f3854\u2033][vc_empty_space height=\u201d50px\u201d][\/vc_column][\/vc_row][vc_row equal_height=\u201dyes\u201d content_placement=\u201dmiddle\u201d css=\u201d.vc_custom_1661418481086{padding-right: 25px !important;padding-left: 25px !important;}\u201d][vc_column css_animation=\u201dleft-to-right\u201d width=\u201d1\/3\u2033 css=\u201d.vc_custom_1617549111049{background-color: #1f3854 !important;}\u201d]<div class=\"ba-partner effect-1 \">\n\t\t\t\t<div class=\"list-item\"><div class=\"partner-item\">\n\t\t\t\t\t\t\t<a  target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"334\" src=\"https:\/\/doratalomran.iq\/wp-content\/uploads\/2021\/04\/alomran-logo-kajaria-white.png\" class=\"attachment-small size-small\" alt=\"\" srcset=\"https:\/\/doratalomran.iq\/wp-content\/uploads\/2021\/04\/alomran-logo-kajaria-white.png 500w, https:\/\/doratalomran.iq\/wp-content\/uploads\/2021\/04\/alomran-logo-kajaria-white-300x200.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a>\n\t\t\t\t\t\t<\/div><\/div>\n\t\t\t<\/div>[\/vc_column][vc_column css_animation=\u201dleft-to-right\u201d width=\u201d1\/3\u2033][vc_single_image image=\u201d3715\u2033 img_size=\u201dfull\u201d css_animation=\u201dappear\u201d][\/vc_column][vc_column css_animation=\u201dright-to-left\u201d width=\u201d1\/3\u2033][vc_custom_heading text=\u201d\u0643\u0627\u062c\u0627\u0631\u064a\u0627\u201d font_container=\u201dtag:h3|font_size:30|text_align:right\u201d use_theme_fonts=\u201dyes\u201d css_animation=\u201dleft-to-right\u201d][vc_column_text]<\/p>\n<p style=\"text-align: right;\"><span style=\"color: #d0af84;\">\u0643\u0627\u062c\u0627\u0631\u064a\u0627 \u0644\u0644\u0628\u0644\u0627\u0637 \u0647\u064a \u0623\u0643\u0628\u0631 \u0634\u0631\u0643\u0629 \u0644\u062a\u0635\u0646\u064a\u0639 \u0627\u0644\u0633\u064a\u0631\u0627\u0645\u064a\u0643\/\u0627\u0644\u0628\u0644\u0627\u0637 \u0627\u0644\u0645\u0632\u062c\u062c \u0641\u064a \u0627\u0644\u0647\u0646\u062f.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=\u201d.vc_custom_1661418486470{padding-right: 25px !important;padding-left: 25px !important;}\u201d][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: right;\">\u0648\u062d\u062f\u0627\u062a \u0627\u0644\u062a\u0635\u0646\u064a\u0639 \u0641\u064a \u0643\u0627\u062c\u0631\u064a\u0629 \u0645\u062c\u0647\u0632\u0629 \u0628\u0623\u062d\u062f\u062b \u0627\u0644\u062a\u0642\u0646\u064a\u0627\u062a \u0627\u0644\u062d\u062f\u064a\u062b\u0629\u060c \u0648\u0627\u0644\u0623\u062a\u0645\u062a\u0629 \u0627\u0644\u0645\u0643\u062b\u0641\u0629\u060c \u0648\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0627\u0644\u0622\u0644\u064a \u0648\u0628\u0627\u0644\u062a\u0627\u0644\u064a \u062a\u0646\u0639\u062f\u0645 \u0641\u0631\u0635\u0629 \u062d\u0635\u0648\u0644 \u0627\u0644\u0623\u062e\u0637\u0627\u0621. \u0647\u0630\u0647 \u0625\u062d\u062f\u0649 \u0627\u0644\u0623\u0633\u0628\u0627\u0628 \u0627\u0644\u0642\u0644\u064a\u0644\u0629 \u0627\u0644\u062a\u064a \u062a\u062c\u0639\u0644 \u0643\u0627\u062c\u0631\u064a\u0629 \u0631\u0627\u0626\u062f\u0629 \u0641\u064a \u0642\u0637\u0627\u0639\u0647\u0627.<\/p>\n<p style=\"text-align: right;\">.\u062a\u0623\u0633\u0633\u062a \u0643\u0627\u062c\u0627\u0631\u064a\u0627 \u0645\u0646\u0630 30 \u0639\u0627\u0645\u0627\u064b \u0648\u0645\u0646 \u062d\u064a\u0646\u0647\u0627 \u0643\u0628\u0631\u062a \u0627\u0644\u0634\u0631\u0643\u0629 \u0648\u062a\u0637\u0648\u0631\u062a \u0628\u0641\u0636\u0644 \u0639\u0645\u0644\u0647\u0627 \u0627\u0644\u062c\u0627\u062f \u0648\u0627\u0628\u062a\u0643\u0627\u0631\u0627\u062a\u0647\u0627 \u0648\u0631\u0639\u0627\u064a\u062a\u0647\u0627 \u0645\u0646 \u0639\u0645\u0644\u0627\u0626\u0647\u0627<\/p>\n<p>[\/vc_column_text][vc_empty_space][vc_btn title=\u201d\u062a\u062d\u0645\u064a\u0644 \u0627\u0644\u0645\u0644\u0641\u201d i_icon_fontawesome=\u201dfas fa-angle-left\u201d css_animation=\u201dflipInY\u201d add_icon=\u201dtrue\u201d link=\u201durl:%23|target:_blank|\u201d][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=\u201d50px\u201d][vc_separator color=\u201dcustom\u201d accent_color=\u201d#1f3854\u2033][vc_empty_space height=\u201d50px\u201d][\/vc_column][\/vc_row][vc_row][vc_column width=\u201d1\/4\u2033][\/vc_column][vc_column width=\u201d1\/2\u2033][vc_custom_heading text=\u201d\u062a\u0633\u062c\u0644 \u0627\u0644\u0622\u0646! \u062a\u0645 \u062a\u0635\u0645\u064a\u0645 \u062f\u0648\u0631\u0627\u062a\u0646\u0627 \u0644\u062a\u0646\u0627\u0633\u0628 \u0627\u062d\u062a\u064a\u0627\u062c\u0627\u062a\u0643.\u201d font_container=\u201dtag:h3|font_size:30|text_align:right\u201d use_theme_fonts=\u201dyes\u201d css_animation=\u201dleft-to-right\u201d][vc_column_text]<\/p>\n<p style=\"text-align: right;\">\u0639\u0644\u0649 \u0645\u0627\u0630\u0627 \u062a\u0631\u064a\u062f \u0627\u0644\u062a\u0631\u0643\u064a\u0632\u061f \u0645\u0627 \u0647\u064a \u0627\u0644\u0623\u0633\u0637\u062d \u0623\u0648 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0637\u0644\u0627\u0621\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u0639\u0645\u0644 \u0628\u0647\u0627\u061f \u0647\u0644 \u062a\u062a\u0637\u0644\u0639 \u0625\u0644\u0649 \u0632\u064a\u0627\u062f\u0629 \u0627\u0644\u0633\u0631\u0639\u0629 \u0623\u0648 \u0627\u0644\u0643\u0641\u0627\u0621\u0629 \u0623\u0648 \u0627\u0644\u062c\u0648\u062f\u0629 \u2013 \u0623\u0645 \u0627\u0644\u062b\u0644\u0627\u062b\u0629 \u062c\u0645\u064a\u0639\u0647\u0627\u061f<\/p>\n<p style=\"text-align: right;\">\u064a\u0645\u0643\u0646 \u062a\u0635\u0645\u064a\u0645 \u062c\u0645\u064a\u0639 \u062f\u0648\u0631\u0627\u062a\u0646\u0627 \u0627\u0644\u062a\u062f\u0631\u064a\u0628\u064a\u0629 \u0644\u062a\u0646\u0627\u0633\u0628 \u0627\u0644\u0627\u062d\u062a\u064a\u0627\u062c\u0627\u062a \u0627\u0644\u0645\u062d\u062f\u062f\u0629 \u0644\u0645\u0648\u0638\u0641\u064a\u0643 \u0648\u0623\u0639\u0645\u0627\u0644\u0643 \u0648\u0645\u0634\u0631\u0648\u0639\u0643. \u064a\u063a\u0637\u064a \u0627\u0644\u0646\u0638\u0631\u064a\u0629 \u0627\u0644\u0623\u0633\u0627\u0633\u064a\u0629 \u0648\u0623\u062d\u062f\u062b \u0627\u0644\u062a\u0637\u0648\u0631\u0627\u062a \u0641\u064a \u062a\u0643\u0646\u0648\u0644\u0648\u062c\u064a\u0627 \u0627\u0644\u0637\u0644\u0627\u0621 \u0648\u0625\u0639\u062f\u0627\u062f \u0627\u0644\u0633\u0637\u062d \u0648\u0637\u0631\u0642 \u0627\u0644\u062a\u0637\u0628\u064a\u0642. \u064a\u0631\u0643\u0632\u0648\u0646 \u0639\u0644\u0649 \u0627\u0644\u0643\u0641\u0627\u0621\u0629 \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u062c\u0648\u062f\u0629 \u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u2013 \u0644\u0645\u0633\u0627\u0639\u062f\u0629 \u0641\u0631\u064a\u0642\u0643 \u0639\u0644\u0649 \u0632\u064a\u0627\u062f\u0629 \u0627\u0644\u0625\u0646\u062a\u0627\u062c\u064a\u0629 \u0648\u062a\u0642\u0644\u064a\u0644 \u0627\u0644\u0641\u0627\u0642\u062f \u0648\u062e\u0641\u0636 \u0627\u0644\u062a\u0643\u0627\u0644\u064a\u0641.<\/p>\n<p>[\/vc_column_text][vc_empty_space height=\u201d50px\u201d]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3003-o1\" lang=\"ar\" dir=\"rtl\" data-wpcf7-id=\"3003\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ar\/wp-json\/wp\/v2\/pages\/2881#wpcf7-f3003-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u0646\u0645\u0648\u0630\u062c \u0627\u0644\u0627\u062a\u0635\u0627\u0644\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"3003\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"ar\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3003-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label>\u0627\u0644\u0627\u0633\u0645 \u0627\u0644\u0627\u0648\u0644 (\u0645\u0637\u0644\u0648\u0628):<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-firstname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"-- \u0627\u0643\u062a\u0628 \u0627\u0633\u0645\u0643 \u0627\u0644\u0623\u0648\u0644 --\" type=\"text\" name=\"your-firstname\" \/><\/span><\/label>\n<\/p>\n<p><label>\u0627\u0633\u0645 \u0627\u0644\u0639\u0627\u0626\u0644\u0629 (\u0645\u0637\u0644\u0648\u0628):<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-lastname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"-- \u0627\u0643\u062a\u0628 \u0627\u0633\u0645 \u0639\u0627\u0626\u0644\u062a\u0643 --\" type=\"text\" name=\"your-lastname\" \/><\/span><\/label>\n<\/p>\n<p><label>\u0639\u0646\u0648\u0627\u0646 \u0628\u0631\u064a\u062f\u0643 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a (\u0645\u0637\u0644\u0648\u0628):<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"-- \u0627\u0643\u062a\u0628 \u0639\u0646\u0648\u0627\u0646 \u0628\u0631\u064a\u062f\u0643 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a --\" type=\"email\" name=\"your-email\" \/><\/span><\/label>\n<\/p>\n<p><label>\u0645\u0627 \u0647\u0648 \u0646\u0648\u0639 \u0627\u0644\u062a\u062f\u0631\u064a\u0628 \u0627\u0644\u0630\u064a \u062a\u0631\u063a\u0628 \u0641\u064a \u0627\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u064a\u0647<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"training-type\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"training-type\"><option value=\"\">-- \u0627\u062e\u062a\u0631 \u0646\u0648\u0639 \u0627\u0644\u062a\u062f\u0631\u064a\u0628 --<\/option><option value=\"\u0627\u0644\u062f\u0647\u0627\u0646\u0627\u062a \u0648\u0627\u0644\u0637\u0644\u0627\u0621\">\u0627\u0644\u062f\u0647\u0627\u0646\u0627\u062a \u0648\u0627\u0644\u0637\u0644\u0627\u0621<\/option><option value=\"\u0627\u0644\u0623\u062f\u0648\u0627\u062a \u0635\u062d\u064a\u0629\">\u0627\u0644\u0623\u062f\u0648\u0627\u062a \u0635\u062d\u064a\u0629<\/option><option value=\"\u0627\u0644\u0628\u0644\u0627\u0637\">\u0627\u0644\u0628\u0644\u0627\u0637<\/option><\/select><\/span><\/label>\n<\/p>\n<p>[group Paints-Coating-training-selected]<br \/>\n<label>\u0645\u0627 \u0647\u0648 \u0645\u0633\u062a\u0648\u0649 \u062e\u0628\u0631\u062a\u0643\u061f<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"field-type\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"field-type\"><option value=\"\">-- \u062d\u062f\u062f \u0645\u0633\u062a\u0648\u0649 \u0627\u0644\u062e\u0628\u0631\u0629 --<\/option><option value=\"\u062f\u0647\u0627\u0646 \u0645\u0628\u062a\u062f\u0623\">\u062f\u0647\u0627\u0646 \u0645\u0628\u062a\u062f\u0623<\/option><option value=\"\u062f\u0647\u0627\u0646 \u0645\u062d\u062a\u0631\u0641\">\u062f\u0647\u0627\u0646 \u0645\u062d\u062a\u0631\u0641<\/option><option value=\"\u0645\u0647\u0646\u062f\u0633\u064a\u0646 \u0648\u0645\u0634\u0631\u0641\u064a\u0646\">\u0645\u0647\u0646\u062f\u0633\u064a\u0646 \u0648\u0645\u0634\u0631\u0641\u064a\u0646<\/option><\/select><\/span><\/label>[\/group]\n<\/p>\n<p>[group Beginner-Painter-course-selected]<br \/>\n<label>\u064a\u0631\u062c\u0649 \u062a\u062d\u062f\u064a\u062f \u0627\u0633\u0645 \u0627\u0644\u062f\u0648\u0631\u0629 \u0627\u0644\u062a\u062f\u0631\u064a\u0628\u064a\u0629 \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u0643<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"course-type\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"course-type\"><option value=\"\">-- \u0627\u062e\u062a\u0631 \u062f\u0648\u0631\u062a\u0643 \u0627\u0644\u062a\u062f\u0631\u064a\u0628\u064a\u0629 --<\/option><option value=\"OG1001 \u0623\u0633\u0627\u0633\u064a\u0627\u062a \u062a\u0637\u0628\u064a\u0642  \u0627\u0644\u062f\u0647\u0627\u0646 \u0627\u0644\u062f\u064a\u0643\u0648\u0631\u064a\">OG1001 \u0623\u0633\u0627\u0633\u064a\u0627\u062a \u062a\u0637\u0628\u064a\u0642  \u0627\u0644\u062f\u0647\u0627\u0646 \u0627\u0644\u062f\u064a\u0643\u0648\u0631\u064a<\/option><\/select><\/span><\/label>\n<\/p>\n<p>OG1001 \u062a\u063a\u0637\u064a \u0627\u0644\u062f\u0648\u0631\u0629 \u0627\u0633\u0627\u0633\u064a\u0627\u062a \u0645\u0647\u0646\u0629 \u0627\u0644\u062f\u0647\u0627\u0646 \u0648\u0645\u0646 \u0627\u0644\u0645\u0631\u0627\u062d\u0644 \u0627\u0644\u0627\u0648\u0644\u064a \u0644\u062a\u0639\u0644\u0645 \u0627\u0644\u0645\u0647\u0646\u0647.(\u0627\u0644\u0645\u062f\u0629: \u062b\u0644\u0627\u062b\u0629 \u0623\u064a\u0627\u0645)\n<\/p>\n<p>[\/group]\n<\/p>\n<p>[group Advanced-Painter-course-selected]<br \/>\n<label>\u064a\u0631\u062c\u0649 \u062a\u062d\u062f\u064a\u062f \u0627\u0633\u0645 \u0627\u0644\u062f\u0648\u0631\u0629 \u0627\u0644\u062a\u062f\u0631\u064a\u0628\u064a\u0629 \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u0643<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"course-type\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"course-type\"><option value=\"\">-- \u0627\u062e\u062a\u0631 \u062f\u0648\u0631\u062a\u0643 \u0627\u0644\u062a\u062f\u0631\u064a\u0628\u064a\u0629 --<\/option><option value=\"OG1002 \u062a\u0642\u0646\u064a\u0627\u062a \u062a\u0637\u0628\u064a\u0642  \u0627\u0644\u062f\u0647\u0627\u0646 \u0627\u0644\u062f\u064a\u0643\u0648\u0631\u064a\">OG1002 \u062a\u0642\u0646\u064a\u0627\u062a \u062a\u0637\u0628\u064a\u0642  \u0627\u0644\u062f\u0647\u0627\u0646 \u0627\u0644\u062f\u064a\u0643\u0648\u0631\u064a<\/option><option value=\"OG1003 \u0627\u0633\u0627\u0633\u064a\u0627\u062a \u062a\u0637\u0628\u064a\u0642 \u0627\u0644\u0637\u0644\u0627\u0626\u0627\u062a \u0627\u0644\u0635\u0646\u0627\u0639\u064a\u0629\">OG1003 \u0627\u0633\u0627\u0633\u064a\u0627\u062a \u062a\u0637\u0628\u064a\u0642 \u0627\u0644\u0637\u0644\u0627\u0626\u0627\u062a \u0627\u0644\u0635\u0646\u0627\u0639\u064a\u0629<\/option><option value=\"OG1004 \u062a\u0642\u0646\u064a\u0627\u062a \u062a\u0637\u0628\u064a\u0642 \u0627\u0644\u0637\u0644\u0627\u0626\u0627\u062a \u0627\u0644\u0635\u0646\u0627\u0639\u064a\u0629\">OG1004 \u062a\u0642\u0646\u064a\u0627\u062a \u062a\u0637\u0628\u064a\u0642 \u0627\u0644\u0637\u0644\u0627\u0626\u0627\u062a \u0627\u0644\u0635\u0646\u0627\u0639\u064a\u0629<\/option><\/select><\/span><\/label>\n<\/p>\n<p>- OG1002 \u062a\u063a\u0637\u064a \u0627\u0644\u062f\u0648\u0631\u0629 \u062a\u0637\u0628\u064a\u0642 \u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0628\u0635\u0648\u0631\u0629 \u0635\u062d\u064a\u062d\u0647 \u0648\u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0627\u062e\u0631 \u0645\u0627 \u062a\u0648\u0635\u0644\u062a \u0627\u0644\u064a\u0629 \u0627\u0644\u062a\u0643\u0646\u0644\u0648\u062c\u064a\u0629 \u0627\u0644\u062d\u062f\u064a\u062b\u0629 \u0641\u064a \u062a\u0637\u0628\u064a\u0642 \u0627\u0644\u062f\u0647\u0627\u0646\u0627\u062a. (\u0627\u0644\u0645\u062f\u0629: \u062b\u0644\u0627\u062b\u0629 \u0623\u064a\u0627\u0645)\n<\/p>\n<p>- OG1003 \u062a\u063a\u0637\u064a \u062f\u0648\u0631\u0629 \u0643\u0644 \u0645\u0627 \u062a\u062d\u062a\u0627\u062c \u0644\u0645\u0639\u0631\u0641\u062a\u0647 \u0639\u0646 \u0627\u0644\u0637\u0644\u0627\u0621 \u0627\u0644\u0635\u0646\u0627\u0639\u064a \u0648\u0627\u0633\u062a\u062a\u062e\u062f\u0627\u0645\u0627\u062a\u0647 (\u0627\u0644\u0645\u062f\u0629: \u064a\u0648\u0645\u0627\u0646)\n<\/p>\n<p>- OG1004 \u062a\u063a\u0637\u064a \u062f\u0648\u0631\u0629 \u0643\u0644 \u0645\u0627 \u062a\u062d\u062a\u0627\u062c \u0644\u0645\u0639\u0631\u0641\u062a\u0647 \u0639\u0646 \u0643\u064a\u0641\u064a\u0629 \u062a\u0637\u0628\u064a\u0642 \u0627\u0644\u0637\u0644\u0627\u0626\u0627\u062a \u0627\u0644\u0635\u0646\u0627\u0639\u064a\u0629\u060c \u0645\u0646 \u062a\u062d\u062f\u064a\u062f \u0623\u0646\u0638\u0645\u0629 \u0627\u0644\u0637\u0644\u0627\u0621 \u0625\u0644\u0649 \u062a\u062d\u062f\u064a\u062f \u0627\u0644\u0623\u0633\u0628\u0627\u0628 \u0627\u0644\u0645\u062d\u062a\u0645\u0644\u0629 \u0644\u0644\u0639\u064a\u0648\u0628. \u064a\u0645\u0646\u062d\u0643 \u0641\u0647\u0645\u064b\u0627 \u0634\u0627\u0645\u0644\u0627\u064b \u0644\u0623\u062f\u0627\u0621 \u0627\u0644\u062a\u0622\u0643\u0644 \u0648\u0627\u0644\u0637\u0644\u0627\u0621 \u060c \u0648\u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0627\u0644\u0623\u062f\u0648\u0627\u062a \u0627\u0644\u0645\u0633\u062a\u062e\u062f\u0645\u0629.(\u0627\u0644\u0645\u062f\u0629: \u062b\u0644\u0627\u062b\u0629 \u0623\u064a\u0627\u0645)\n<\/p>\n<p>[\/group]\n<\/p>\n<p>[group engineer-supervisors-course-selected]<br \/>\n<label>\u064a\u0631\u062c\u0649 \u062a\u062d\u062f\u064a\u062f \u0627\u0633\u0645 \u0627\u0644\u062f\u0648\u0631\u0629 \u0627\u0644\u062a\u062f\u0631\u064a\u0628\u064a\u0629 \u0627\u0644\u062e\u0627\u0635\u0629 \u0628\u0643<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"course-type\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"course-type\"><option value=\"\">-- \u0627\u062e\u062a\u0631 \u062f\u0648\u0631\u062a\u0643 \u0627\u0644\u062a\u062f\u0631\u064a\u0628\u064a\u0629 --<\/option><option value=\"OG1005 \u062f\u0648\u0631\u0629 \u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u062f\u064a\u0643\u0648\u0631\u064a\u0629\">OG1005 \u062f\u0648\u0631\u0629 \u0627\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u062f\u064a\u0643\u0648\u0631\u064a\u0629<\/option><option value=\"OG1006 \u062f\u0648\u0631\u0629 \u0641\u062d\u0635 \u0627\u0644\u0637\u0644\u0627\u0621 \u0627\u0644\u0635\u0646\u0627\u0639\u064a\">OG1006 \u062f\u0648\u0631\u0629 \u0641\u062d\u0635 \u0627\u0644\u0637\u0644\u0627\u0621 \u0627\u0644\u0635\u0646\u0627\u0639\u064a<\/option><option value=\"OG1008 \u0636\u0645\u0627\u0646 \u0648\u0645\u0631\u0627\u0642\u0628\u0629 \u0627\u0644\u062c\u0648\u062f\u0629\">OG1008 \u0636\u0645\u0627\u0646 \u0648\u0645\u0631\u0627\u0642\u0628\u0629 \u0627\u0644\u062c\u0648\u062f\u0629<\/option><\/select><\/span><\/label>\n<\/p>\n<p>- OG1005 \u062a\u063a\u0637\u064a \u062f\u0648\u0631\u0629 \u0643\u0644 \u0645\u0627 \u062a\u062d\u062a\u0627\u062c \u0644\u0645\u0639\u0631\u0641\u062a\u0647 \u0639\u0646 \u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u062f\u064a\u0643\u0648\u0631\u064a\u0629 \u0648\u0627\u0633\u062a\u062e\u062f\u0627\u0645\u0627\u062a\u0647\u0645 .(\u0627\u0644\u0645\u062f\u0629: \u064a\u0648\u0645\u0627\u0646)\n<\/p>\n<p>- OG1006 \u0633\u062a\u0645\u0646\u062d\u0643 \u0647\u0630\u0647 \u0627\u0644\u062f\u0648\u0631\u0629 \u0627 \u0641\u0647\u0645\u064b\u0627 \u0646\u0638\u0631\u064a\u064b\u0627 \u0648\u062a\u0645\u0643\u0646\u0643 \u0645\u0646 \u0625\u062c\u0631\u0627\u0621 \u0639\u0645\u0644\u064a\u0627\u062a \u062a\u0641\u062a\u064a\u0634 \u0646\u0645\u0648\u0630\u062c\u064a\u0629 \u0641\u064a\u0645\u0627 \u064a\u062a\u0639\u0644\u0642 \u0628\u0627\u0644\u062d\u0645\u0627\u064a\u0629 \u0645\u0646 \u0627\u0644\u062a\u0622\u0643\u0644. \u062a\u0647\u062f\u0641 \u0627\u0644\u062f\u0648\u0631\u0629 \u0625\u0644\u0649 \u0627\u0644\u0645\u0634\u0631\u0641\u064a\u0646 \u0627\u0644\u0645\u062d\u062a\u0645\u0644\u064a\u0646 \u0648\u0627\u0644\u0645\u0645\u062b\u0644\u064a\u0646 \u0627\u0644\u062a\u0642\u0646\u064a\u064a\u0646 \u0627\u0644\u0622\u062e\u0631\u064a\u0646 \u0645\u0646 \u0627\u0644\u0635\u0646\u0627\u0639\u0627\u062a \u0627\u0644\u062b\u0642\u064a\u0644\u0629 \u060c \u0627\u0644\u0628\u0631\u064a\u0629 \u0648\u0627\u0644\u0628\u062d\u0631\u064a\u0629 \u0648\u0627\u0644\u0628\u062d\u0631\u064a\u0629 \u0627\u0644\u0630\u064a\u0646 \u064a\u0624\u062f\u0648\u0646 \u0623\u0648 \u064a\u062e\u0637\u0637\u0648\u0646 \u0644\u062a\u0648\u0644\u064a \u0645\u0647\u0627\u0645 \u0627\u0644\u0625\u0634\u0631\u0627\u0641 \u0623\u0648 \u0627\u0644\u062a\u0641\u062a\u064a\u0634. (\u0627\u0644\u0645\u062f\u0629: \u064a\u0648\u0645\u0627\u0646)\n<\/p>\n<p>- OG1008 \u0643\u064a\u0641 \u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u062a\u0623\u0643\u062f \u0645\u0646 \u0627\u0633\u062a\u064a\u0641\u0627\u0621 \u062c\u0645\u064a\u0639 \u0627\u0644\u0623\u0639\u0645\u0627\u0644 \u0644\u0644\u0645\u0648\u0627\u0635\u0641\u0627\u062a \u0648\u0645\u0639\u0627\u064a\u064a\u0631 \u0627\u0644\u062c\u0648\u062f\u0629 \u0627\u0644\u0645\u0637\u0644\u0648\u0628\u0629\u061f \u064a\u063a\u0637\u064a \u062a\u062f\u0631\u064a\u0628\u0646\u0627 \u0644\u0636\u0645\u0627\u0646 \u0627\u0644\u062c\u0648\u062f\u0629 \u0648\u0645\u0631\u0627\u0642\u0628\u0629 \u0627\u0644\u062c\u0648\u062f\u0629 \u0643\u0644 \u0645\u0627 \u062a\u062d\u062a\u0627\u062c\u0647 \u0644\u0636\u0645\u0627\u0646 \u062c\u0648\u062f\u0629 \u062c\u064a\u062f\u0629 \u0641\u064a \u062c\u0645\u064a\u0639 \u0623\u0646\u062d\u0627\u0621 \u0627\u0644\u0645\u0634\u0631\u0648\u0639 \u060c \u0645\u0646 \u0641\u0647\u0645 \u0645\u062a\u0637\u0644\u0628\u0627\u062a \u0627\u0644\u0645\u0648\u0627\u0635\u0641\u0627\u062a \u0625\u0644\u0649 \u0625\u0639\u062f\u0627\u062f \u0627\u0644\u0633\u0637\u062d \u0648\u0627\u0644\u062a\u0637\u0628\u064a\u0642 \u0648\u0627\u0644\u0641\u062d\u0635. (\u0627\u0644\u0645\u062f\u0629: \u064a\u0648\u0645\u0627\u0646)\n<\/p>\n<p>[\/group]\n<\/p>\n<p>[group Sanitary-Training-selected]<br \/>\n<label>Where is your business located?<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"continent\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"continent\"><option value=\"\">-- Choose your continent --<\/option><option value=\"Europe\">Europe<\/option><option value=\"America\">America<\/option><option value=\"Africa\">Africa<\/option><option value=\"Asia\">Asia<\/option><option value=\"Oceania\">Oceania<\/option><option value=\"Antarctica\">Antarctica<\/option><\/select><\/span><\/label><br \/>\n[\/group]\n<\/p>\n<p><label>\u0644\u0644\u0627\u0633\u062a\u0641\u0633\u0627\u0631\u0627\u062a<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"comments\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"comments\"><\/textarea><\/span><\/label><br \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"\u0625\u0631\u0633\u0627\u0644\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[vc_empty_space height=\u201d50px\u201d][\/vc_column][vc_column width=\u201d1\/4\u2033][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_height=\u201dyes\u201d equal_height=\u201dyes\u201d content_placement=\u201dmiddle\u201d css=\u201d.vc_custom_1661418423047{padding-right: 25px !important;padding-left: 25px !important;}\u201d][vc_column width=\u201d1\/2\u2033][vc_column_text] \u062c\u0647\u0632 \u062c\u062f\u0631\u0627\u0646\u0643 \u0648\u0623\u0631\u0636\u064a\u0627\u062a\u0643 \u0628\u0623\u0641\u0636\u0644 \u0645\u0627 \u064a\u0643\u0648\u0646. \u0645\u0627 \u064a\u0645\u064a\u0632 \u0627\u0644\u0628\u0644\u0627\u0637 \u0639\u0646 \u063a\u064a\u0631\u0647 \u0645\u0646 \u0645\u0648\u0627\u062f \u0627\u0644\u062a\u0635\u0645\u064a\u0645 \u0647\u0648 \u062a\u0639\u062f\u062f \u0627\u0633\u062a\u062e\u062f\u0627\u0645\u0627\u062a\u0647 \u2013 \u062a\u0632\u064a\u064a\u0646 \u062c\u062f\u0631\u0627\u0646 \u0627\u0644\u0645\u0637\u0628\u062e \u0648\u0623\u0631\u0636\u064a\u0627\u062a \u0627\u0644\u062d\u0645\u0627\u0645 \u0641\u064a \u0627\u0644\u0645\u0646\u0632\u0644 \u0648\u0625\u0636\u0627\u0641\u0629 \u0637\u0627\u0628\u0639\u064b\u0627 \u0645\u0645\u064a\u0632\u064b\u0627 \u0625\u0644\u0649 \u0623\u0631\u0636\u064a\u0627\u062a \u0627\u0644\u0645\u0645\u0631\u0627\u062a \u0648\u062c\u062f\u0631\u0627\u0646 \u063a\u0631\u0641\u0629 \u0627\u0644\u0645\u0639\u064a\u0634\u0629. \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u062a\u0639\u062f\u062f \u0627\u0633\u062a\u062e\u062f\u0627\u0645\u0627\u062a\u0647\u060c \u064a\u062a\u0645\u064a\u0632 \u0627\u0644\u0628\u0644\u0627\u0637 \u0628\u0645\u062c\u0645\u0648\u0639\u0629 \u0643\u0628\u064a\u0631\u0629 \u0645\u0646 \u0627\u0644\u0641\u0648\u0627\u0626\u062f \u0627\u0644\u0639\u0645\u0644\u064a\u0629 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","footnotes":""},"class_list":["post-2881","page","type-page","status-publish","hentry","no-thumb"],"_links":{"self":[{"href":"https:\/\/doratalomran.iq\/ar\/wp-json\/wp\/v2\/pages\/2881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/doratalomran.iq\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/doratalomran.iq\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/doratalomran.iq\/ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/doratalomran.iq\/ar\/wp-json\/wp\/v2\/comments?post=2881"}],"version-history":[{"count":6,"href":"https:\/\/doratalomran.iq\/ar\/wp-json\/wp\/v2\/pages\/2881\/revisions"}],"predecessor-version":[{"id":4200,"href":"https:\/\/doratalomran.iq\/ar\/wp-json\/wp\/v2\/pages\/2881\/revisions\/4200"}],"wp:attachment":[{"href":"https:\/\/doratalomran.iq\/ar\/wp-json\/wp\/v2\/media?parent=2881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}